{"id":474,"date":"2019-01-25T10:24:59","date_gmt":"2019-01-25T16:24:59","guid":{"rendered":"https:\/\/www.staptraveltours.com\/blog2\/wordpress\/?p=474"},"modified":"2023-02-20T14:19:43","modified_gmt":"2023-02-20T20:19:43","slug":"la-capital-americana-de-la-cultura","status":"publish","type":"post","link":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/","title":{"rendered":"La capital americana de la cultura."},"content":{"rendered":"<h3><span class=\"ez-toc-section\" id=\"Merida_es_una_de_las_ciudades_en_Mexico_en_la_que_se_respira_tranquilidad_dia_con_dia_y_una_de_las_mas_hermosas_de_la_Peninsula_de_Yucatan\"><\/span>M\u00e9rida, es una de las ciudades en M\u00e9xico en la que se respira tranquilidad d\u00eda con d\u00eda y una de las m\u00e1s hermosas de la Pen\u00ednsula de Yucat\u00e1n.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"http:\/\/www.staptraveltours.com\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-475\" src=\"https:\/\/www.staptraveltours.com\/blog2\/wordpress\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg 1280w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/maxresdefault-300x169.jpg 300w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/maxresdefault-768x432.jpg 768w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/maxresdefault-1024x576.jpg 1024w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/maxresdefault-750x422.jpg 750w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_45_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" area-label=\"ez-toc-toggle-icon-1\"><label for=\"item-6a580d3bdacea\" aria-label=\"Table of Content\"><span style=\"display: flex;align-items: center;width: 35px;height: 30px;justify-content: center;direction:ltr;\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/label><input  type=\"checkbox\" id=\"item-6a580d3bdacea\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/#Merida_es_una_de_las_ciudades_en_Mexico_en_la_que_se_respira_tranquilidad_dia_con_dia_y_una_de_las_mas_hermosas_de_la_Peninsula_de_Yucatan\" title=\"M\u00e9rida, es una de las ciudades en M\u00e9xico en la que se respira tranquilidad d\u00eda con d\u00eda y una de las m\u00e1s hermosas de la Pen\u00ednsula de Yucat\u00e1n.\">M\u00e9rida, es una de las ciudades en M\u00e9xico en la que se respira tranquilidad d\u00eda con d\u00eda y una de las m\u00e1s hermosas de la Pen\u00ednsula de Yucat\u00e1n.<\/a><ul class='ez-toc-list-level-4'><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/#Conoce_mas\" title=\"Conoce m\u00e1s:\">Conoce m\u00e1s:<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>La belleza colonial y tradicional de sus calles y su gente amable hacen que M\u00e9rida sea un lugar con elegancia adem\u00e1s de que cuenta con la mejor gastronom\u00eda de la regi\u00f3n. La plaza mayor es el lugar ideal para pasar una tarde tranquila con toda la familia ya que es el lugar perfecto para reunirse y disfrutar de m\u00fasica, baile y comida.<\/p>\n<p><strong>\u00bfQu\u00e9 visitar?<\/strong><\/p>\n<p><strong>Gran Museo del Mundo Maya.<\/strong><\/p>\n<p>Si eres amante de la historia y quieres conocer el origen de la cultura maya, este es el lugar indicado, donde podr\u00e1s hallar todas las respuestas. El museo cuenta con las mejores instalaciones y con innovadoras propuestas de interacci\u00f3n que te sorprender\u00e1n.<\/p>\n<p><strong>Parque Zool\u00f3gico del Centenario.<\/strong><\/p>\n<p>En este parque podr\u00e1s divertirte con toda la familia ya que es un lugar con muchos atractivos donde aprender\u00e1s todo sobre los animales que habitan dentro.<\/p>\n<p><strong>Catedral de Yucat\u00e1n.<\/strong><\/p>\n<p>La catedral se encuentra en el centro hist\u00f3rico de la ciudad y es la primera catedral levantada en Am\u00e9rica continental y el m\u00e1s antiguo de la regi\u00f3n.<\/p>\n<p><strong>Paseo Montejo.<\/strong><\/p>\n<p>El tradicional paseo Montejo es el lugar donde podr\u00e1s admirar viejos y hermosas cas de la \u00e9poca del porfiriato.<\/p>\n<p>M\u00e9rida es excelente para visitar con toda la familia y sobretodo disfrutar de la ciudad m\u00e1s hermosa y tranquila de Yucat\u00e1n\u00ad\u00ad\u00ad\u00ad\u00ad.<\/p>\n<div id='gallery-1' class='gallery galleryid-474 gallery-columns-5 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-11-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-11-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-11-1-300x300.jpg 300w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-11-1-150x150.jpg 150w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-11-1-768x768.jpg 768w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-11-1-750x750.jpg 750w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-11-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-12-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-12-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-12-1-300x300.jpg 300w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-12-1-150x150.jpg 150w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-12-1-768x768.jpg 768w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-12-1-750x750.jpg 750w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-12-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-14-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-14-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-14-1-300x300.jpg 300w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-14-1-150x150.jpg 150w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-14-1-768x768.jpg 768w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-14-1-750x750.jpg 750w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-14-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-13-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-13-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-13-1-300x300.jpg 300w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-13-1-150x150.jpg 150w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-13-1-768x768.jpg 768w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-13-1-750x750.jpg 750w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-13-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-15-1.jpg'><img width=\"300\" height=\"300\" src=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-15-1-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-15-1-300x300.jpg 300w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-15-1-150x150.jpg 150w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-15-1-768x768.jpg 768w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-15-1-750x750.jpg 750w, https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/blog-imagen-15-1.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h4><span class=\"ez-toc-section\" id=\"Conoce_mas\"><\/span>Conoce m\u00e1s:<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><a href=\"http:\/\/www.staptraveltours.com\">http:\/\/www.staptraveltours.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9rida, es una de las ciudades en M\u00e9xico en la que se respira tranquilidad d\u00eda con d\u00eda y una de las m\u00e1s hermosas de la Pen\u00ednsula de Yucat\u00e1n. La belleza colonial y tradicional de sus calles y su gente amable hacen que M\u00e9rida sea un lugar con elegancia adem\u00e1s de que cuenta con la mejor &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/\"> <span class=\"screen-reader-text\">La capital americana de la cultura.<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.0 (Yoast SEO v20.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La capital americana de la cultura. - Stap Travel Tours<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La capital americana de la cultura.\" \/>\n<meta property=\"og:description\" content=\"M\u00e9rida, es una de las ciudades en M\u00e9xico en la que se respira tranquilidad d\u00eda con d\u00eda y una de las m\u00e1s hermosas de la Pen\u00ednsula de Yucat\u00e1n. La belleza colonial y tradicional de sus calles y su gente amable hacen que M\u00e9rida sea un lugar con elegancia adem\u00e1s de que cuenta con la mejor &hellip; La capital americana de la cultura. Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/\" \/>\n<meta property=\"og:site_name\" content=\"Stap Travel Tours\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-25T16:24:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T20:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/merida.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"509\" \/>\n\t<meta property=\"og:image:height\" content=\"339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Mote\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Mote\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La capital americana de la cultura. - Stap Travel Tours","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/","og_locale":"es_MX","og_type":"article","og_title":"La capital americana de la cultura.","og_description":"M\u00e9rida, es una de las ciudades en M\u00e9xico en la que se respira tranquilidad d\u00eda con d\u00eda y una de las m\u00e1s hermosas de la Pen\u00ednsula de Yucat\u00e1n. La belleza colonial y tradicional de sus calles y su gente amable hacen que M\u00e9rida sea un lugar con elegancia adem\u00e1s de que cuenta con la mejor &hellip; La capital americana de la cultura. Leer m\u00e1s &raquo;","og_url":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/","og_site_name":"Stap Travel Tours","article_published_time":"2019-01-25T16:24:59+00:00","article_modified_time":"2023-02-20T20:19:43+00:00","og_image":[{"width":509,"height":339,"url":"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2019\/01\/merida.jpg","type":"image\/jpeg"}],"author":"Antonio Mote","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Mote","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/#article","isPartOf":{"@id":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/"},"author":{"name":"Antonio Mote","@id":"https:\/\/www.staptraveltours.com\/blog\/#\/schema\/person\/00a4057462a6dcc93bbf5314cf607b23"},"headline":"La capital americana de la cultura.","datePublished":"2019-01-25T16:24:59+00:00","dateModified":"2023-02-20T20:19:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/www.staptraveltours.com\/blog\/#organization"},"inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/","url":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/","name":"La capital americana de la cultura. - Stap Travel Tours","isPartOf":{"@id":"https:\/\/www.staptraveltours.com\/blog\/#website"},"datePublished":"2019-01-25T16:24:59+00:00","dateModified":"2023-02-20T20:19:43+00:00","breadcrumb":{"@id":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.staptraveltours.com\/blog\/la-capital-americana-de-la-cultura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.staptraveltours.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La capital americana de la cultura."}]},{"@type":"WebSite","@id":"https:\/\/www.staptraveltours.com\/blog\/#website","url":"https:\/\/www.staptraveltours.com\/blog\/","name":"Stap Travel Tours","description":"Un vistazo a nuestras aventuras por el mundo","publisher":{"@id":"https:\/\/www.staptraveltours.com\/blog\/#organization"},"alternateName":"Stap Travel Tours","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.staptraveltours.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.staptraveltours.com\/blog\/#organization","name":"Stap Travel & Tours","alternateName":"Stap Travel & Tours","url":"https:\/\/www.staptraveltours.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.staptraveltours.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2023\/02\/stap-icono_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/www.staptraveltours.com\/blog\/wp-content\/uploads\/2023\/02\/stap-icono_Mesa-de-trabajo-1.png","width":283,"height":283,"caption":"Stap Travel & Tours"},"image":{"@id":"https:\/\/www.staptraveltours.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.staptraveltours.com\/blog\/#\/schema\/person\/00a4057462a6dcc93bbf5314cf607b23","name":"Antonio Mote","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.staptraveltours.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f290708906b03fc508d4611e38a1b4fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f290708906b03fc508d4611e38a1b4fa?s=96&d=mm&r=g","caption":"Antonio Mote"},"sameAs":["https:\/\/antoniomote.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/posts\/474"}],"collection":[{"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/comments?post=474"}],"version-history":[{"count":1,"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/posts\/474\/revisions"}],"predecessor-version":[{"id":952,"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/posts\/474\/revisions\/952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/media\/951"}],"wp:attachment":[{"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/media?parent=474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/categories?post=474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.staptraveltours.com\/blog\/wp-json\/wp\/v2\/tags?post=474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}